{"id":1487,"date":"2023-05-09T09:06:23","date_gmt":"2023-05-09T07:06:23","guid":{"rendered":"https:\/\/premiummagnets.de\/?post_type=dt_portfolio&#038;p=1487"},"modified":"2024-03-11T16:20:12","modified_gmt":"2024-03-11T15:20:12","slug":"magnetabscheider-fuer-pneumatische-foerderung","status":"publish","type":"dt_portfolio","link":"https:\/\/premiummagnets.de\/index.php\/project\/magnetabscheider-fuer-pneumatische-foerderung\/","title":{"rendered":"PNEUMAG &#8211; Magnetabscheider &#8211; exakt abgestimmt auf pneumatische F\u00f6rderung"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8220;1\/2&#8243;]<div class=\"standard-arrow list-divider bullet-top\"><ul>\n<li>Separieren eisenhaltige und paramagnetische Verunreinigungen<\/li>\n<li>Zur Untersuchung rieself\u00e4higer Sch\u00fcttg\u00fcter<\/li>\n<li>Leichte Handhabung und Reinigung<\/li>\n<li>K\u00f6nnen einfach in bestehende Anlagen integriert werden<\/li>\n<li>Optimales Preis-\/Leistungsverh\u00e4ltnis<\/li>\n<li>Kurze Lieferzeit<\/li>\n<\/ul>\n<\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;]<div class=\"standard-arrow list-divider bullet-top\"><ul>\n<li>Extrem hohe Magnetkr\u00e4fte bis max. 14 300 Gau\u00df<\/li>\n<li>EASY CLEAN Ausf\u00fchrung zur einfachen Abreinigung erh\u00e4ltlich<\/li>\n<li>Robuste und verschlei\u00dfbest\u00e4ndige Edelstahlh\u00fclsen (1.4404)<\/li>\n<li>Kundenspezifische Durchmesser und Abmessungen<\/li>\n<li>zum Einsatz in ATEX-Zone 20 geeignet<\/li>\n<li>FDA konforme Ausf\u00fchrung<\/li>\n<li>Pharma Ausf\u00fchrung optional<\/li>\n<\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row type=&#8220;vc_default&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_masonry_media_grid element_width=&#8220;12&#8243; grid_id=&#8220;vc_gid:1710170390757-cf6c8523-c869-1&#8243; include=&#8220;1512&#8243;][vc_separator][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_column_text]<\/p>\n<h3><strong>PNEUMAG &#8211; Magnetabscheider f\u00fcr pneumatische F\u00f6rderung<\/strong><strong>:<\/strong><\/h3>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Die Ausstattung mit zwei versetzt angeordneten Magnetstabreihen und die Verwendung des Hochenergie-Neodym mit einer Wirkkraft von 12 000 Gau\u00df an der Staboberfla\u0308che erlauben es, selbst feine Eisenverunreinigungen sowie magnetisierte Edelstahlpartikel sicher aus dem Produktstrom abzuscheiden.<\/p>\n<p>Alle Oberfla\u0308chen sind aus verschlei\u00dffestem Edelstahl 1.4404 gefertigt und innen sowie au\u00dfen poliert (Ra=1,2\u03bcm). Fu\u0308r den Einsatz in der pharmazeutischen Industrie sind die Oberfla\u0308chengu\u0308ten\u00a0nochmals verbessert (Ra=0,6\u03bcm). Standardma\u0308\u00dfig wird der Rohrmagnet PNEUMAG mit EASY CLEAN Abreinigung angeboten, d.h. die\u00a0Magnetkerne ko\u0308nnen aus den Edelstahlhu\u0308lsen gezogen werden, wodurch alle abgeschiedenen Verunreinigungen abfallen. Mit Hilfe dieser Einrichtung wird die Reinigung des Systems erheblich vereinfacht und beschleunigt. Um einen unerlaubten Zugriff zu verhindern wird der Magnetseparator inklusive einer Schutzabdeckung mit Bu\u0308gelschlo\u00df ausgeliefert. Getestet und zertifiziert wird das System PNEUMAG bis zu einem Druck von +\/-1 bar. Premium Magnets bietet daru\u0308ber hinaus auch Varianten fu\u0308r den U\u0308berdruckbereich bis zu + 5 bar an.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Hauptkomponenten:<\/strong><\/p>\n<ul>\n<li>Edelstahlausf\u00fchrung mit polierten Oberfl\u00e4chen<\/li>\n<li>Versetzt \u00fcbereinander angeordnete Neodym-Magnetst\u00e4be<\/li>\n<li>Anschluss mittels gelaserten Flachflanschen oder benutzerdefinierten Anschl\u00fcssen<\/li>\n<li>Einteilige Geh\u00e4usedichtung (FDA konform\/Metalldetektierbar)<\/li>\n<li>EASY CLEAN Ausf\u00fchrung<\/li>\n<\/ul>\n<h3><strong>Typische Einsatzbereiche:<\/strong><\/h3>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dieser spezielle Rohrmagnet wurde fu\u0308r den Einsatz in Saug- und Druckfo\u0308rderleitungen mit ho\u0308heren Stro\u0308mungsgeschwindigkeiten (bis zu 25m\/s) konzipiert. Die Haupteinsatzgebiete<br \/>\nsind die Lebensmittel- und Pharmaindustrie mit Produkten wie zum Beispiel Mehl, Zucker, Sta\u0308rke,\u00a0Pharmawirkstoffe und weitere feinko\u0308rnige sowie pulverfo\u0308rmige Materialien. Die besondere Bauform ermo\u0308glicht einen Produktfluss\u00a0in beiden Richtungen durch das System. Der Magnetabscheider kann nach Kundenwunsch mit den verschiedensten Anschlu\u0308ssen gefertigt werden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>weitere Einsatzbereiche:<\/p>\n<ul>\n<li>Kunststoffindustrie<\/li>\n<li>Lebensmittelindustrie<\/li>\n<li>Chemische Industrie<\/li>\n<li>Pharmazeutische Industrie<\/li>\n<li>Textilindustrie<\/li>\n<li>Holzindustrie<\/li>\n<li>Recyclingindustrie<\/li>\n<li>Verpackungsindustrie<\/li>\n<\/ul>\n<p>Andere Industriezweige[\/vc_column_text]<span id=\"creative-link-wrap-5827\" class=\"ult_main_cl ult-adjust-bottom-margin  \" >\n\t \t\t\t<span class=\"ult_cl_link_3  ult_crlink\" >\n\t\t\t\t\t<a  data-ultimate-target='#creative-link-wrap-5827 .ult_colorlink'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  href=\"javascript:void(0);\"  class=\"ult_colorlink ult-responsive \" style=\"float:left;font-weight:bold; \"  data-textcolor=\"#333333\" data-texthover=\"#eabd07\"data-style=\"Style_3\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span data-hover=\"F\u00fcr Anwendungen im freier Fall gehts hier zu unserem Abscheider Magbox\" style=\"color:#333333;;;\" class=\"ult_btn10_span   \">F\u00fcr Anwendungen im freier Fall gehts hier zu unserem Abscheider Magbox<\/span>\n\t\t\t\t\t\t<span class=\"ult_link_btm3 \" style=\"border-color:#333333;border-bottom-width:1px;border-style:solid;\"><\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t<\/span>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2026-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"2026\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/1487#wpcf7-f2026-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2026\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2026-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label>Name (Pflichtfeld)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label>E-Mail-Adresse (Pflichtfeld)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> Firma<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Firma\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Firma\" \/><\/span> <\/label><br \/>\n<label> Telefon<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"Telefon\" \/><\/span> <\/label><br \/>\n<label> Hier k\u00f6nnen Sie Fragen oder Informationen zu Anwendung eingeben<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Freitext\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Freitext\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Mehr Informationen anfordern\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Magnetgittersystem im Geh\u00e4use zum Einbau in pneumatische F\u00f6rderleitungen mit hohen Str\u00f6mungsgeschwindigkeiten (bis 25 m\/s) oder Freifallleitungen. Optional in Pharma-Ausf\u00fchrung mit hochpolierten Oberfl\u00e4chen erh\u00e4ltlich.<\/p>\n","protected":false},"author":1,"featured_media":1490,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[58,54,50,33,51,48,42,35,37,49,59,55,56,53,57],"dt_portfolio_tags":[163],"class_list":["post-1487","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-anwendungen","dt_portfolio_category-branchen","dt_portfolio_category-chemie","dt_portfolio_category-freifallanwendungen","dt_portfolio_category-kunststoff","dt_portfolio_category-lebensmittel","dt_portfolio_category-pneumag","dt_portfolio_category-magnetgitter","dt_portfolio_category-magnetgitter-im-gehaeuse","dt_portfolio_category-pharma","dt_portfolio_category-pneumatische-foerderung","dt_portfolio_category-produkte","dt_portfolio_category-recycling","dt_portfolio_category-textil-fasern-papier","dt_portfolio_category-tierfutter","dt_portfolio_tags-magnetgitter","dt_portfolio_category-58","dt_portfolio_category-54","dt_portfolio_category-50","dt_portfolio_category-33","dt_portfolio_category-51","dt_portfolio_category-48","dt_portfolio_category-42","dt_portfolio_category-35","dt_portfolio_category-37","dt_portfolio_category-49","dt_portfolio_category-59","dt_portfolio_category-55","dt_portfolio_category-56","dt_portfolio_category-53","dt_portfolio_category-57","description-off"],"_links":{"self":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/1487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/comments?post=1487"}],"version-history":[{"count":21,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/1487\/revisions"}],"predecessor-version":[{"id":2302,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/1487\/revisions\/2302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/media\/1490"}],"wp:attachment":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/media?parent=1487"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio_category?post=1487"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio_tags?post=1487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}