{"id":2062,"date":"2024-02-19T14:52:13","date_gmt":"2024-02-19T13:52:13","guid":{"rendered":"https:\/\/premiummagnets.de\/?post_type=dt_portfolio&#038;p=2062"},"modified":"2024-03-20T09:02:13","modified_gmt":"2024-03-20T08:02:13","slug":"gebrauchter_magnetseparator-pneumag-125","status":"publish","type":"dt_portfolio","link":"https:\/\/premiummagnets.de\/index.php\/project\/gebrauchter_magnetseparator-pneumag-125\/","title":{"rendered":"Gebrauchter Magnetseparator PNEUMAG &#8211; f\u00fcr pneumatische F\u00f6rderung"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8220;1\/2&#8243;]<div class=\"standard-arrow list-divider bullet-top\"><ul>\n<li>Separieren eisenhaltige und paramagnetische Verunreinigungen<\/li>\n<li>Zur Untersuchung rieself\u00e4higer Sch\u00fcttg\u00fcter<\/li>\n<li>Leichte Handhabung und Reinigung<\/li>\n<li>K\u00f6nnen einfach in bestehende Anlagen integriert werden<\/li>\n<li>Optimales Preis-\/Leistungsverh\u00e4ltnis<\/li>\n<li>Ab Lager lieferbar (Zwischenverkauf vorbehalten)<\/li>\n<\/ul>\n<\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;]<div class=\"standard-arrow list-divider bullet-top\"><ul>\n<li>Extrem hohe Magnetkr\u00e4fte bis max. 13700 Gauss<\/li>\n<li>9000 Gauss Wirkkraft an der Magnetoberfl\u00e4che<\/li>\n<li>EASY CLEAN Ausf\u00fchrung zur einfachen Abreinigung<\/li>\n<li>Robuste und verschlei\u00dfbest\u00e4ndige Edelstahlh\u00fclsen (1.4404)<\/li>\n<li>zum Einsatz in ATEX-Zone 20 geeignet<\/li>\n<li>FDA konforme Ausf\u00fchrung<\/li>\n<\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row type=&#8220;vc_default&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_masonry_media_grid element_width=&#8220;12&#8243; grid_id=&#8220;vc_gid:1710921715068-c8f7d5b0-07a4-10&#8243; include=&#8220;2064,2067,1512&#8243;][vc_separator][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_column_text]<\/p>\n<h3><strong>Gebrauchter Magnetseparator PNEUMAG &#8211; f\u00fcr pneumatische F\u00f6rderung:<\/strong><\/h3>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Die Ausstattung mit zwei versetzt angeordneten Magnetstabreihen und die Verwendung des Hochenergie-Neodym mit einer Wirkkraft von \u00a09000 Gauss an der Staboberfla\u0308che erlauben es, selbst feine Eisenverunreinigungen sowie magnetisierte Edelstahlpartikel sicher aus dem Produktstrom abzuscheiden.<\/p>\n<p>Alle Oberfla\u0308chen sind aus verschlei\u00dffestem Edelstahl 1.4404 gefertigt und geb\u00fcrstet, die Magneth\u00fclsen poliert (Ra=1,2\u03bcm). Der Rohrmagnet PNEUMAG verf\u00fcgt \u00fcber eine \u00a0EASY CLEAN Abreinigung, \u00a0d.h. die Magnetkerne ko\u0308nnen aus den Edelstahlhu\u0308lsen gezogen werden, wodurch alle abgeschiedenen Verunreinigungen abfallen. Mit Hilfe dieser Einrichtung wird die Reinigung des Systems erheblich vereinfacht und beschleunigt. Um einen unerlaubten Zugriff zu verhindern wird der Magnetseparator inklusive einer Schutzabdeckung mit Bu\u0308gelschlo\u00df ausgeliefert. Getestet und zertifiziert ist das System PNEUMAG bis zu einem Druck von +\/-1 bar.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Hauptkomponenten:<\/strong><\/p>\n<ul>\n<li>Edelstahlausf\u00fchrung mit geb\u00fcrsteten Oberfl\u00e4chen, Magneth\u00fclsen poliert<\/li>\n<li>Versetzt \u00fcbereinander angeordnete Neodym-Magnetst\u00e4be<\/li>\n<li>Anschluss mittels gelasertem Flachflansch DIN 2576 PN10 DN125 6mm aus- und einlaufseitig<\/li>\n<li>Einteilige Geh\u00e4usedichtung (FDA konform\/metalldetektierbar)<\/li>\n<li>EASY CLEAN Ausf\u00fchrung<\/li>\n<\/ul>\n<h3><strong>Typische Einsatzbereiche:<\/strong><\/h3>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dieser spezielle Rohrmagnet wurde fu\u0308r den Einsatz in Saug- und Druckfo\u0308rderleitungen mit ho\u0308heren Stro\u0308mungsgeschwindigkeiten (bis zu 25m\/s) konzipiert. Die Haupteinsatzgebiete<br \/>\nsind die Lebensmittel- und Pharmaindustrie mit Produkten wie zum Beispiel Mehl, Zucker, Sta\u0308rke, Pharmawirkstoffe und weitere feinko\u0308rnige sowie pulverfo\u0308rmige Materialien. Die besondere Bauform ermo\u0308glicht einen Produktfluss in beiden Richtungen durch das System.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>weitere Einsatzbereiche:<\/p>\n<ul>\n<li>Kunststoffindustrie<\/li>\n<li>Lebensmittelindustrie<\/li>\n<li>Chemische Industrie<\/li>\n<li>Pharmazeutische Industrie<\/li>\n<li>Textilindustrie<\/li>\n<li>Holzindustrie<\/li>\n<li>Recyclingindustrie<\/li>\n<li>Verpackungsindustrie<\/li>\n<\/ul>\n<p>Andere Industriezweige<\/p>\n<p><strong>Gebrauchtger\u00e4t : Das Ger\u00e4t weist durch kurzzeitigen Einsatz leichte Gebrauchsspuren auf\u00a0<\/strong>[\/vc_column_text]<span id=\"creative-link-wrap-3456\" class=\"ult_main_cl ult-adjust-bottom-margin  \" >\n\t \t\t\t<span class=\"ult_cl_link_3  ult_crlink\" >\n\t\t\t\t\t<a  data-ultimate-target='#creative-link-wrap-3456 .ult_colorlink'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  href=\"https:\/\/premiummagnets.de\/index.php\/project\/magnetabscheider-fuer-pneumatische-foerderung\/\"  class=\"ult_colorlink ult-responsive \" style=\"float:left;font-weight:bold; \"  data-textcolor=\"#333333\" data-texthover=\"#eabd07\"data-style=\"Style_3\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span data-hover=\"F\u00fcr Neuger\u00e4te in anderen Abmessungen und mit anderen Anschl\u00fcssen hier mehr Details\" style=\"color:#333333;;;\" class=\"ult_btn10_span   \">F\u00fcr Neuger\u00e4te in anderen Abmessungen und mit anderen Anschl\u00fcssen hier mehr Details<\/span>\n\t\t\t\t\t\t<span class=\"ult_link_btm3 \" style=\"border-color:#333333;border-bottom-width:1px;border-style:solid;\"><\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t<\/span>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2141-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"2141\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/2062#wpcf7-f2141-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2141\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2141-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label>Name (Pflichtfeld)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label>E-Mail-Adresse (Pflichtfeld)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> Firma<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Firma\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Firma\" \/><\/span> <\/label><br \/>\n<label> Telefon<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"Telefon\" \/><\/span> <\/label><br \/>\n<label> Hier k\u00f6nnen Sie Fragen oder Informationen zu Anwendung eingeben<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Freitext\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Freitext\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Angebot f\u00fcr diese Ger\u00e4t anfordern\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Magnetgittersystem im Geh\u00e4use zum Einbau in pneumatische F\u00f6rderleitungen mit hohen Str\u00f6mungsgeschwindigkeiten (bis 25 m\/s) oder Freifallleitungen. Optional in Pharma-Ausf\u00fchrung mit hochpolierten Oberfl\u00e4chen erh\u00e4ltlich.<\/p>\n","protected":false},"author":1,"featured_media":2063,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[200],"dt_portfolio_tags":[],"class_list":["post-2062","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-magnet-gebraucht","dt_portfolio_category-200","description-off"],"_links":{"self":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/2062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/comments?post=2062"}],"version-history":[{"count":13,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/2062\/revisions"}],"predecessor-version":[{"id":2408,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio\/2062\/revisions\/2408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/media\/2063"}],"wp:attachment":[{"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/media?parent=2062"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio_category?post=2062"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/premiummagnets.de\/index.php\/wp-json\/wp\/v2\/dt_portfolio_tags?post=2062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}